{"id":848,"date":"2023-06-28T15:31:03","date_gmt":"2023-06-28T14:31:03","guid":{"rendered":"http:\/\/www.esquisses.eu\/revue\/?p=848"},"modified":"2023-09-09T17:29:27","modified_gmt":"2023-09-09T16:29:27","slug":"ecrire-la-nuit-caio-vinicius-russo-nogueira","status":"publish","type":"post","link":"https:\/\/www.esquisses.eu\/revue\/ecrire-la-nuit-caio-vinicius-russo-nogueira\/","title":{"rendered":"\u00c9crire, la nuit \u2014 Caio Vin\u00edcius Russo Nogueira"},"content":{"rendered":"\n<div class=\"wp-block-buttons is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.esquisses.eu\/revue\/wp-content\/uploads\/2023\/09\/NUIT_Revue_Esquisses_No5-3.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Nuit, le PDF<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-justify\">\u00ab&nbsp;<em>Une mouche \u00e9ph\u00e9m\u00e8re na\u00eet \u00e0 neuf heures du matin dans les grands jours d\u2019\u00e9t\u00e9, pour mourir \u00e0 cinq heures du soir ; comment comprendrait-elle le mot nuit ?&nbsp;<\/em>\u00bb<em> <\/em> <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Stendhal <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La naissance de la lumi\u00e8re, r\u00e9sistance de la nuit <\/strong> <\/h2>\n\n\n\n<p class=\"has-text-align-justify\">Avant la lumi\u00e8re, la nuit \u00e9tait l\u00e0. Mais pas m\u00eame le dieu jud\u00e9o-chr\u00e9tien n&rsquo;a pu supporter la nuit, l&rsquo;intensit\u00e9 informe de la nuit, l&rsquo;impersonnalit\u00e9 de la nuit. Le <em>Fiat Lux <\/em>est l\u2019\u00e9chec devant la nuit, l\u2019\u00e9chec devant l\u2019indiscernable de la nuit, devant l&rsquo;amn\u00e9sie sans contradiction ni m\u00e9moire de la nuit. La naissance de la lumi\u00e8re est aussi la naissance de la dialectique, la naissance de la nuit. La naissance de la division, des \u00e9carts. Le r\u00e8glement des distributions. L\u2019invention de la nuit en tant qu&rsquo;opposition \u00e0 la lumi\u00e8re. Et soudain tout est clair. On peut identifier les choses. Il y a \u00ab&nbsp;\u00e7a&nbsp;\u00bb et \u00ab&nbsp;\u00e7a&nbsp;\u00bb. On peut discerner les choses. Il y a \u00ab&nbsp;celui-ci&nbsp;\u00bb et \u00ab&nbsp;celui-l\u00e0&nbsp;\u00bb. On peut voir. Il y a les formes et les mati\u00e8res. On peut savoir des choses. Il y a des \u00e9tants class\u00e9s selon leur genre et leur esp\u00e8ce. On peut mesurer les distances entre les choses. Il y a le proche, le lointain, l\u2019ordinaire et le paysage. On peut partager le monde, mais on peut aussi discriminer le monde, le d\u00e9crire. Voil\u00e0 la naissance de l\u2019analyse : la s\u00e9paration gr\u00e2ce \u00e0 la lumi\u00e8re. N\u2019est-il pas curieux que la nuit soit d\u00e9finie, m\u00eame si elle existe avant son invention, avant sa naissance, en tant que n\u00e9gativit\u00e9 de la lumi\u00e8re, en tant que quelque chose qui manque, l&rsquo;absence de lumi\u00e8re, la contradiction, c\u2019est-\u00e0-dire la non-lumi\u00e8re ? Mais la nuit est toujours l\u00e0. La nuit r\u00e9siste.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Si la philosophie ne s&rsquo;envole qu&rsquo;au cr\u00e9puscule, \u00e0 la limite du jour, le vol de l&rsquo;ind\u00e9cision, la litt\u00e9rature a toujours \u00e9t\u00e9 du c\u00f4t\u00e9 de la nuit, sensation de la nuit dans la nuit. La litt\u00e9rature est la nuit. Et la nuit est le d\u00e9sert, l&rsquo;\u0153uf&nbsp;; mais on ne peut pas aller trop vite\u2026 Pourtant ce n\u2019est pas par hasard que les trahisons se passent dans la nuit. Il y a la peur de la nuit. La peur de la trahison pendant la nuit. La peur aussi du \u00ab&nbsp;distinct obscur&nbsp;\u00bb de la nuit, l\u2019Id\u00e9e.<sup><a href=\"#sdfootnote1sym\"><sup>1<\/sup><\/a><\/sup> Mais de quelle mani\u00e8re peut-on discerner dans la nuit ? On est seul dans la nuit, dans le silence de la nuit. On ne peut pas nommer dans le silence de la nuit, mais on peut glorifier dans la nuit.<sup><a href=\"#sdfootnote2sym\"><sup>2<\/sup><\/a><\/sup> On n&rsquo;est personne dans la nuit. On ne peut pas dire. On ne peut rien voir. On est aveugle. C\u2019est la bonne question, voir ? A-t-on vraiment besoin de \u00ab&nbsp;la&nbsp;\u00bb lumi\u00e8re pour voir ? A-t-on besoin de voir ? Le probl\u00e8me des habitants des grottes de Platon ce n\u2019est peut-\u00eatre pas la nuit, ce sont les ombres, c\u2019est-\u00e0-dire l&rsquo;illusion \u00e0 cause de la lumi\u00e8re. Il n\u2019y a pas d&rsquo;illusion dans la nuit parce qu&rsquo;il n\u2019y a pas de s\u00e9paration entre la v\u00e9rit\u00e9 et l&rsquo;erreur. Il y a seulement l\u2019int\u00e9ressant.<sup><a href=\"#sdfootnote3sym\"><sup>3<\/sup><\/a><\/sup> Il faut donc \u00e9teindre les feux, souffler les bougies que l\u2019on croit encore allum\u00e9es. Et \u00e9teindre c&rsquo;est d\u00e9j\u00e0 \u00e9crire, c\u2019est d\u00e9j\u00e0 la nuit. Ce sont de tr\u00e8s bons \u00e9crivains mais il leur manque la nuit.<sup><a href=\"#sdfootnote4sym\"><sup>4<\/sup><\/a><\/sup> On n\u2019\u00e9crit jamais avec les bougies. Parfois avec une ampoule, mais plus souvent une ampoule cass\u00e9e.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">En-de\u00e7\u00e0 d\u2019Apollon, mais aussi de Dionysos : Nix. Les Occidentaux, m\u00eame si ce syntagme ne veut presque rien dire, n\u2019aiment pas la nuit, ni les ombres.<sup><a href=\"#sdfootnote5sym\"><sup>5<\/sup><\/a><\/sup> Lumi\u00e8re, lumi\u00e8re partout ! On ne peut pas supporter la nuit. La lumi\u00e8re est la domestication. L\u2019\u00e9loge de l&rsquo;exactitude. La volont\u00e9 de pr\u00e9cision. Explicitation. Pas d\u2019ivresse. M\u00eame si l\u2019ivresse, c\u2019est l&rsquo;absolu.<sup><a href=\"#sdfootnote6sym\"><sup>6<\/sup><\/a><\/sup> M\u00eame si l\u2019ivresse c\u2019est d\u00e9j\u00e0 la nuit. On a besoin de lumi\u00e8re quand m\u00eame ! On a beaucoup progress\u00e9 ! On a conquis l\u2019Am\u00e9rique ! Voulez-vous un lustre ? N\u2019avez-vous pas besoin d\u2019une marquise \u2013 et elle peut ou non sortir \u00e0 17h \u2013, d\u2019un roi, d\u2019un pape ?  M\u00eame les colonis\u00e9s le croient parfois, et encore. M\u00eame les \u00e9crivains le croient parfois, et encore. La nuit r\u00e9siste ? <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Contre l\u2019opinion, \u00e9crire lucioles<\/strong><\/h2>\n\n\n\n<p class=\"has-text-align-justify\">Quel bonheur parler des choses, des gens, des \u00e9v\u00e8nements&nbsp;! Quel bonheur donner notre avis&nbsp;! On se r\u00e9veille et il y a le flux, l\u2019in\u00e9puisable flux des donn\u00e9es, le cours continu des nouvelles, l\u2019imp\u00e9ratif de l\u2019information. On peut se communiquer, on peut faire quelque chose de <em>commun<\/em>, trouver un sol illumin\u00e9 sans la nuit. On peut diss\u00e9miner notre parole dans les r\u00e9seaux sociaux, mais on peut aussi se nourrir des autres paroles, paroles lointaines, de n\u2019importe o\u00f9, de n\u2019importe qui.  <\/p>\n\n\n\n<p class=\"has-text-align-justify\">L\u2019information est le jour. Elle commence avec le jour en tant que partie m\u00eame du jour. \u00catre inform\u00e9. Savoir ce qui se passe. \u00catre d\u2019accord ou \u00eatre en dispute (presque la m\u00eame chose, d\u2019ailleurs). C\u2019est vraiment le jour, participation dans la lumi\u00e8re, dans le <em>socius<\/em>&nbsp;: partager le monde, prendre notre parti, <em>mais juste la part qui nous revient dans \u00ab&nbsp;notre place&nbsp;\u00bb<\/em>. On est tous sous le m\u00eame soleil, mais dans le partage sous le soleil il y a le lieu, \u00ab&nbsp;notre lieu&nbsp;\u00bb, on peut voir les traces, les cercles, la limite, la contrainte, m\u00eame si on peut donner notre opinion \u00ab&nbsp;librement&nbsp;\u00bb, de bonne volont\u00e9.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">L\u2019opinion est le jour. Le royaume de l\u2019opinion est partout. Comme dans l\u2019empire de Charles V, le soleil ne se couche jamais dans le royaume de l\u2019opinion. Mais on a besoin de donner une opinion. La plus haute n\u00e9cessit\u00e9, donner son avis, formuler une opinion, se positionner. \u00ab&nbsp;Mais comment se fait-il que vous ne connaissiez pas ce sujet ?&nbsp;Comment se fait-il que vous n&rsquo;ayez pas d&rsquo;opinion <em>form\u00e9e<\/em> ?&nbsp;\u00bb Et, au-del\u00e0 des sp\u00e9cialistes de l\u2019opinion, c\u2019est bien cela, <em>donner <\/em>notre opinion, comme un <em>don, <\/em>mais aussidonner un contour, une forme.  <\/p>\n\n\n\n<p class=\"has-text-align-justify\">L\u2019opinion est gratuite et sacr\u00e9e, un droit. La libert\u00e9 d\u2019\u00ab exprimer&nbsp;\u00bb son opinion est l\u2019illusion de la lumi\u00e8re. Et qui r\u00e9siste \u00e0 donner son avis, \u00e0 pr\u00e9senter son opinion, \u00e0 la faire circuler dans le commun&nbsp;? Mais l\u2019opinion est lisse, sans bruit, elle ne peut pas dire ce que nous ne savons pas encore, mieux, elle ne peut pas nous affecter, cr\u00e9er des <em>affects.<\/em><a href=\"#sdfootnote7sym\"><sup>7<\/sup><\/a> L\u2019opinion est le cercle infini d\u2019un jour sans nuit, et c\u2019est pour cela que nous sommes insensibles, non-affectables aux opinions.  <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Lord Chandos<a href=\"#sdfootnote8sym\"><sup>8<\/sup><\/a> ne pouvait plus \u00e9crire, lui, ne pouvait pas donner son avis, son opinion. L\u2019aristocratisme&nbsp;? C\u2019est \u00e7a&nbsp;? Pas du tout. On ne peut pas \u00e9crire avec les opinions, les opinions sont le pouvoir du toujours dit, les avis sont donn\u00e9s d\u00e8s le d\u00e9part. Lord Chandos savait que l&rsquo;\u00e9criture se passe ailleurs, dans la nuit des d\u00e9tails, dans la fragmentation sans socle des choses elles-m\u00eames insignifiantes dans l\u2019\u00e9conomie g\u00e9n\u00e9rale des jours. Il ne pouvait plus \u00e9crire <em>sur <\/em>les gens, <em>juger<\/em> les gens. Les conversations lui semblaient d\u00e9plorables. M\u00eame les plus simples, les plus quotidiennes. Il ne pouvait plus \u00e9crire sous les auspices ni de l\u2019opinion ni de la grande harmonie de la religion, il avait besoin de traverser avec ses pens\u00e9es ces \u00ab&nbsp;toiles d\u2019araign\u00e9e&nbsp;\u00bb pour \u00ab&nbsp;d\u00e9boucher sur le vide&nbsp;\u00bb.  <\/p>\n\n\n\n<p class=\"has-text-align-justify\">L\u2019opinion est toujours tr\u00e8s large, \u00e9crasante. Elle manque les d\u00e9tails parce qu&rsquo;elle est comme un immense t\u00e9lescope cass\u00e9 sur lequel s\u2019illumine la fausse clart\u00e9 des mondes possibles. Tout a \u00e9t\u00e9 dit ! Tout a \u00e9t\u00e9 pens\u00e9 ! Tout a \u00e9t\u00e9 \u00e9crit ! Il n&rsquo;y a rien de nouveau sous le soleil. Lord Chandos songeait \u00e9crire diff\u00e9remment, avec une loupe, avec un \u00ab&nbsp;microscope au bout de la peau de son petit doigt \u00bb. Il avait besoin de voir et de toucher en m\u00eame temps.  Lord Chandos cherchait les lucioles.       <\/p>\n\n\n\n<p class=\"has-text-align-justify\">La nuit est d\u00e9mocratique, ou plut\u00f4t anarchique, il n\u2019y a pas de lieu dans la nuit, il n\u2019y a pas de partage. Elle est l\u2019illimit\u00e9, la nuit. De toute fa\u00e7on, on ne peut pas habiter la nuit. La nuit c\u2019est un lieu de passage. La nuit c\u2019est un voyage. Et on a besoin quand m\u00eame de voler de nuit. Juste voler dans le voyage de la nuit. Mais c\u2019est trop dangereux, la nuit. M\u00eame la promesse de la nuit. Parfois il y a des le\u00e7ons \u00e0 prendre chez les insectes. M\u00eame avec la mort d\u2019une mouche sur un mur.<sup><a href=\"#sdfootnote9sym\"><sup>9<\/sup><\/a><\/sup> Et entre la nuit du vide et la lumi\u00e8re des grandes villes, parmi les lumi\u00e8res de l\u2019opinion qui emp\u00eachent le sommeil, le repos, il y a les lucioles.<sup><a href=\"#sdfootnote10sym\"><sup>10<\/sup><\/a><\/sup> On peut \u00e9crire avec des lucioles. Le devenir-luciole de l\u2019\u00e9crivain. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Les lucioles \u00e9mettent de la lumi\u00e8re, mais une lumi\u00e8re faible, une lumi\u00e8re qui ne d\u00e9fait pas la nuit comme l\u2019opinion, mais compose avec la nuit, le devenir-nuit de la luciole \u2013 il y a des lucioles m\u00eame dans l&rsquo;enfer.<a href=\"#sdfootnote11sym\"><sup>11<\/sup><\/a> Mais la lumi\u00e8re de la luciole n&rsquo;est pas vraiment de la lumi\u00e8re. Ce sont des petites lumi\u00e8res, une multiplicit\u00e9 de <em>quasi <\/em>lumi\u00e8res dispers\u00e9es dans l&rsquo;espace sans centre ordonn\u00e9. Les lumi\u00e8res des lucioles sont des <em>indices <\/em>de lumi\u00e8res, la r\u00e9sistance de la nuit, l\u2019esth\u00e9tique de la nuit. Ce sont des petites lumi\u00e8res qui ne d\u00e9voilent rien. On peut presque voir avec les lumi\u00e8res des lucioles. Et il y a un ab\u00eeme entre <em>presque<\/em> voir et voir, entre voir et voler. Les lucioles volent la nuit. Et les lucioles sont aussi l&rsquo;\u00e9blouissement aveuglant d\u2019\u00e9crire au-del\u00e0 de l\u2019opinion. L\u2019\u00e9blouissement de la nuit, de l\u2019Id\u00e9e, de la sensation. Et on suit aveugle la distinction sans r\u00e9f\u00e9rence de l\u2019Id\u00e9e obscure qui m\u00e8ne \u00e0 l&rsquo;impersonnalit\u00e9 d\u2019\u00e9crire, la disparition, la nuit.  <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Il n\u2019y a personne dans la nuit. Il n\u2019y a pas de visages dans la nuit, ni m\u00eame de masques, qui sont d\u00e9j\u00e0 des visages.<sup><a href=\"#sdfootnote12sym\"><sup>12<\/sup><\/a><\/sup> Il n\u2019y a pas d\u2019opinions. Il n\u2019y a pas de signifiants. Il n\u2019y a pas de sens cach\u00e9. Il n\u2019y a pas de secret. Il n\u2019y a pas d&rsquo;au-del\u00e0. On peut presque voir quelque chose, quelqu\u2019un, mais juste <em>presque<\/em>, quand on \u00e9crit. C\u2019est l\u2019insinuation impr\u00e9cise, virtuelle, la nuit. On ne peut jamais \u00ab&nbsp;mettre au point&nbsp;\u00bb dans la nuit, donner notre avis. Et la luciole n\u2019est pas un point, elle est le point en mouvement, \u00e7a veut dire tout autre chose, la danse du point, des points, parce que ce sont des lucioles, au pluriel. On peut presque voir gr\u00e2ce \u00e0 la danse des lucioles, la danse de la nuit. C&rsquo;est pour \u00e7a qu\u2019on peut \u00e9crire avec les lucioles, on \u00e9crit lucioles, on \u00e9crit des visions sans visible de la nuit. Mais on ne peut jamais \u00e9crire avec notre opinion sous un soleil de plomb, ni penser, exister, vivre enfin. On peut tuer quelqu&rsquo;un \u00e0 cause du soleil.<sup><a href=\"#sdfootnote13sym\"><sup>13<\/sup><\/a><\/sup><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Il est clair qu\u2019on peut repr\u00e9senter la nuit, donner une opinion sur la nuit. On peut \u00e9crire <em>sur <\/em>la nuit d\u2019un point de vue assez stable, pr\u00e9cis, \u00e7a veut dire le point de vue de la lumi\u00e8re. Mais il s\u2019agit vraiment de la nuit, la repr\u00e9sentation de la nuit ? N\u2019est-ce pas cela une photo-graphie de la nuit ? Il faut sans doute regarder la nuit.<sup><a href=\"#sdfootnote14sym\"><sup>14<\/sup><\/a><\/sup> Ne pas photographier la nuit, immobiliser la nuit. Juste la regarder. On \u00e9crit avec les lucioles, on \u00e9crit lucioles pour rendre sensible la nuit, pour faire venir la nuit, l\u2019esth\u00e9tique de la nuit, contre les opinions. Esquisser la nuit, \u00e9crire. Mais il y a trop de lumi\u00e8re dans une repr\u00e9sentation, dans une opinion. La repr\u00e9sentation est le lever, le lever du jour. La nuit, elle ne se l\u00e8ve pas, elle tombe. La chute sans repr\u00e9sentation de la nuit, l&rsquo;affect, les lucioles.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>L\u2019\u0153uf, la nuit<\/strong><\/h2>\n\n\n\n<p class=\"has-text-align-justify\">On ne peut pas fuir pendant la journ\u00e9e. Martin, le personnage de <em>La pomme dans le noir<\/em>, de Clarice Lispector<sup><a href=\"#sdfootnote15sym\"><sup>15<\/sup><\/a><\/sup>, ne fuit qu\u2019avant l\u2019arriv\u00e9e du matin. Il peut m\u00eame s\u2019endormir de fatigue pendant la nuit, pendant la fuite. Mais le soleil du jour qui le r\u00e9veille brise sa volont\u00e9 de fuir. Mais il fuit quand m\u00eame, fuit avec le geste de la nuit, le geste qui se prolonge, le geste nocturne qui donne des forces pour fuir m\u00eame pendant la journ\u00e9e avec le soleil blessant. Martin se croit un criminel.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Toute l&rsquo;\u0153uvre de Clarice a \u00e9t\u00e9 compos\u00e9e avec la nuit, dans la nuit en tant qu&rsquo;esth\u00e9tique de la nuit. <em>L&rsquo;\u0153uf et la poule<\/em><sup><a href=\"#sdfootnote16sym\"><sup>16<\/sup><\/a><\/sup>, c&rsquo;est un texte exemplaire de la nuit, c\u2019est compl\u00e8tement la nuit, ce texte-l\u00e0, la nuit tout enti\u00e8re, la fuite de la nuit :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p class=\"has-text-align-justify\"> \u00ab&nbsp;L&rsquo;\u0153uf est une chose suspendue. Il ne s&rsquo;est jamais pos\u00e9. Quand il se pose, ce n&rsquo;est pas lui qui s&rsquo;est pos\u00e9, c&rsquo;est une surface qui est venue se fixer sous l&rsquo;\u0153uf. \u2013 Je regarde l&rsquo;\u0153uf dans la cuisine avec une attention superficielle pour ne pas le casser. Je prends le plus grand soin de ne pas le comprendre. Puisqu&rsquo;il est impossible de le comprendre, je sais que si je le comprends, c&rsquo;est une erreur de ma part [&#8230;] L&rsquo;\u0153uf vit en fuite car il est toujours trop en avance sur son temps. &#8211; L&rsquo;\u0153uf par cons\u00e9quent sera toujours r\u00e9volutionnaire. &#8211; Il vit dans la poule pour ne pas \u00eatre trait\u00e9 de blanc. L&rsquo;\u0153uf de fait est blanc. Mais il ne peut pas \u00eatre trait\u00e9 de blanc. Non pas parce que \u00e7a lui fait mal, \u00e0 lui \u00e0 qui rien ne fait mal, mais les gens qui affirment que l&rsquo;\u0153uf est blanc, ces gens meurent \u00e0 la vie. Dire blanc ce qui est blanc peut d\u00e9truire l&rsquo;humanit\u00e9. La v\u00e9rit\u00e9 d\u00e9truit toujours l&rsquo;humanit\u00e9&nbsp;\u00bb.<sup><a href=\"#sdfootnote17sym\"><sup>17<\/sup><\/a><\/sup><\/p>\n<\/blockquote>\n\n\n\n<p class=\"has-text-align-justify\">A-t-on besoin de commenter cet extrait ? A-t-on besoin de l\u2019interpr\u00e9ter ? A-t-on besoin de traduire l\u2019\u0153uf ? De dire la v\u00e9rit\u00e9 de l\u2019\u0153uf ? On ne peut pas supporter la nuit. Mais c\u2019est quoi \u00e7a ?! On a fait des calculs ! Les r\u00e9volutions ne sont pas possibles, pire encore les r\u00e9volutions d\u2019un \u0153uf ! Il n\u2019y a jamais eu de r\u00e9volutions ! C\u2019est pour \u00e7a que les r\u00e9actionnaires ont horreur de la nuit. M\u00eame s\u2019ils font parfois \u00e9clore des \u0153ufs.  <\/p>\n\n\n\n<p>L&rsquo;\u0153uf est politique. L&rsquo;\u0153uf est la promesse suspendue, mais m\u00eame la promesse de la nuit, de la nuit suspendue, c\u2019est tr\u00e8s dangereux. Quelques \u00e9crivains et artistes prennent le parti de l&rsquo;\u0153uf. L\u2019\u0153uf est blanc, mais blanc ne veut rien dire. Et ils le savent, les \u00e9crivains, les artistes de la nuit. L&rsquo;\u0153uf est indiff\u00e9rent devant le signifiant blanc. On est toujours autour d\u2019un \u0153uf mais si on ne sait pas qu\u2019on est autour d\u2019un \u0153uf c\u2019est parce que, lui, il n&rsquo;a pas de centre.  <\/p>\n\n\n\n<p class=\"has-text-align-justify\">L&rsquo;\u0153uf est la nuit. L&rsquo;\u0153uf danse. Mais c\u2019est tr\u00e8s obscur, un \u0153uf, une Id\u00e9e. On a besoin de lucioles. On ne peut pas comprendre, pas vraiment, un \u0153uf, la nuit. Comprendre, c\u2019est d\u00e9j\u00e0 l\u2019identifier, le signifier, le casser, ce pour quoi on fabrique des poules, pour cacher l\u2019\u0153uf, la nuit :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p class=\"has-text-align-justify\">\n\u00ab&nbsp;En\nce qui concerne le corps de la poule, le corps de la poule est la\nplus grande tentative de preuve que l&rsquo;\u0153uf n&rsquo;existe pas. Car il\nsuffit de regarder la poule pour qu&rsquo;il semble \u00e9vident que l&rsquo;\u0153uf est\ndans l&rsquo;impossibilit\u00e9 d&rsquo;exister. Et la poule ? [&#8230;] La poule regarde\nl&rsquo;horizon. Comme si c&rsquo;\u00e9tait de la ligne d&rsquo;horizon que pouvait venir\nun \u0153uf. Hormis le fait d&rsquo;\u00eatre un moyen de transport pour l&rsquo;\u0153uf, la\npoule est stupide, d\u00e9s\u0153uvr\u00e9e et myope. Comment la poule\npourrait-elle se comprendre alors qu&rsquo;elle est la contradiction d&rsquo;un\n\u0153uf ? L&rsquo;\u0153uf est encore le m\u00eame \u0153uf originaire de la Mac\u00e9doine.\nMais la poule est toujours la trag\u00e9die la plus moderne. Elle est\ntoujours inutilement au courant. Et constamment redessin\u00e9e&nbsp;\u00bb.<sup><a href=\"#sdfootnote18sym\"><sup>18<\/sup><\/a><\/sup><\/p>\n<\/blockquote>\n\n\n\n<p class=\"has-text-align-justify\">La poule est myope parce qu&rsquo;elle croit voir l&rsquo;\u0153uf, savoir ce que c\u2019est un \u0153uf. La poule guette l&rsquo;\u0153uf \u00e0 l\u2019horizon car elle ne sait pas que l&rsquo;\u0153uf est l\u2019horizon suspendu, la nuit.  La poule aime en secret l&rsquo;\u0153uf. Mais il n\u2019y a pas de secret, lui, l&rsquo;\u0153uf, n\u2019est jamais cach\u00e9. L&rsquo;\u0153uf est le non-savoir. Et la nuit est blanche, blanche comme un \u0153uf sans le signifiant blanc.  <\/p>\n\n\n\n<p class=\"has-text-align-justify\">N\u00e9anmoins Clarice ne s&rsquo;int\u00e9resse pas \u00e0 la linguistique, Clarice ne fait pas de la philosophie dans <em>L&rsquo;\u0153uf et la poule<\/em>. Ce n\u2019est m\u00eame pas une r\u00e9flexion, quelque chose comme un essai. Peut-\u00eatre qu&rsquo;on pourrait s\u2019en remettre \u00e0 la rh\u00e9torique sp\u00e9culative de Quignard.<a href=\"#sdfootnote19sym\"><sup>19<\/sup><\/a> Le langage en tant que pens\u00e9e physique des mots et non une mani\u00e8re de traverser avec les mots, avec l\u2019aide des mots, avec le m\u00e9pris des mots, les signifiants sur les mots, pour arriver aux objets, aux conclusions ; \u00e9crire imm\u00e9diatement les mots, prendre les mots \u00e0 la <em>littera<\/em>, \u00e7a veut dire \u00e9crire des images, images de la nuit avec les lucioles, esth\u00e9tique de la nuit, litt\u00e9rature.  <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Mais c\u2019est trop difficile d\u2019\u00e9crire, d\u2019\u00e9crire la nuit, d\u2019\u00e9crire un \u0153uf avec des lucioles quand on est une poule. La poule n\u2019est pas un animal nocturne. Elle se r\u00e9veille tr\u00e8s t\u00f4t. Elle ne vit qu&rsquo;en mangeant des miettes autour d&rsquo;elle. Elle ne chasse pas, pas vraiment. Elle ne cherche pas, pas vraiment. La poule est un animal r\u00e9flexif. Elle trouve. Elle retourne la terre pour trouver des vers et des lombrics sur le sol. Elle d\u00e9voile la vie souterraine. Elle est satisfaite, heureuse de son sort. C\u2019est pour cela que la poule ne veut pas s\u2019enfoncer dans la nuit : elle se croit plus originale que l&rsquo;\u0153uf. Mais elle ne peut pas concevoir l\u2019id\u00e9e d\u2019un \u0153uf. Elle le cr\u00e9e sans le savoir. La poule, elle, craint la nuit, les sensations de la nuit, l\u2019esth\u00e9tique de la nuit, la poule craint l\u2019\u0153uf :      <\/p>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<p class=\"has-text-align-justify\"> \u00ab&nbsp;La poule qui ne voulait pas sacrifier sa vie. Celle qui a choisi d&rsquo;\u00eatre \u00ab heureuse \u00bb. Celle qui ne se rendant pas compte que si elle passait sa vie \u00e0 dessiner l&rsquo;\u0153uf en elle comme une enluminure, elle servirait. Celle qui ne savait pas se perdre [&#8230;] Celle qui a pens\u00e9 que le plaisir \u00e9tait pour elle un don, sans se rendre compte qu&rsquo;il servait \u00e0 la distraire totalement, tandis que l&rsquo;\u0153uf se formerait. Celle qui ne savait pas que \u00ab moi \u00bb est seulement un des mots que l&rsquo;on dessine lorsqu&rsquo;on r\u00e9pond au t\u00e9l\u00e9phone, une simple tentative de chercher une forme plus ad\u00e9quate. Celle qui a pens\u00e9 que \u00ab moi \u00bb signifiait avoir un soi-m\u00eame. Les poules nuisibles pour l&rsquo;\u0153uf sont celles qui sont un \u00ab moi \u00bb sans tr\u00eave. Chez elles le \u00ab moi \u00bb est si constant qu&rsquo;elles ne peuvent plus prononcer le mot \u00ab \u0153uf \u00bb. Mais, qui sait, c&rsquo;est justement de cela que l&rsquo;\u0153uf a besoin. Car si elles n&rsquo;\u00e9taient pas si distraites, si elles pr\u00eataient attention \u00e0 la grande vie qui se fait en elles, elles perturberaient l&rsquo;\u0153uf&nbsp;\u00bb.<sup><a href=\"#sdfootnote20sym\"><sup>20<\/sup><\/a><\/sup><\/p>\n<\/blockquote>\n\n\n\n<p class=\"has-text-align-justify\">\u00c9crire apr\u00e8s Clarice, c\u2019est tr\u00e8s difficile. M\u00eame si on ne veut pas expliquer, traduire, casser l&rsquo;\u0153uf pour le rendre mangeable. L&rsquo;\u0153uf cass\u00e9, c\u2019est une autre chose, un incorporel, l\u2019expression, un pur \u00e9v\u00e9nement qui change l&rsquo;\u0153uf, le sens.<sup><a href=\"#sdfootnote21sym\"><sup>21<\/sup><\/a><\/sup> On peut toujours casser l&rsquo;\u0153uf, mais c&rsquo;est un proc\u00e9d\u00e9 tr\u00e8s banal. On peut toujours croire que c\u2019est un Moi qui casse l&rsquo;\u0153uf, mais c\u2019est un proc\u00e9d\u00e9 tr\u00e8s vulgaire. L&rsquo;\u0153uf ne veut pas attirer l\u2019attention. Mais il a besoin de la distraction d\u2019une poule justement car il est tr\u00e8s discret, lui, l&rsquo;\u0153uf, la nuit. Mais il est tr\u00e8s difficile quand m\u00eame de parler de l\u2019\u0153uf sans le casser car on ne peut m\u00eame pas voir Clarice. On a commenc\u00e9 o\u00f9 exactement ? Quand ? L&rsquo;\u0153uf est un d\u00e9sert. Un vide ? L&rsquo;\u0153uf est une vie. L&rsquo;\u0153uf est une \u00e9criture. On a commenc\u00e9 \u00e0 quel point de d\u00e9part ? On a esquiss\u00e9 un faux d\u00e9but avec Dieu et la Gen\u00e8se. On a commenc\u00e9 au milieu, bien s\u00fbr, car il n\u2019y a pas de d\u00e9but de la nuit, ni de pr\u00e9lude pour un \u0153uf. Mais o\u00f9 ?  En-de\u00e7\u00e0 de la lumi\u00e8re ?  Dans la nuit ?  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Note sur l&rsquo;auteur<\/h2>\n\n\n\n<p>Caio Vin\u00edcius Russo Nogueira est \u00e9crivain et doctorant en Th\u00e9orie Litt\u00e9raire et Litt\u00e9rature Compar\u00e9e par l\u2019Universit\u00e9 de S\u00e3o Paulo (USP) et chercheur invit\u00e9 \u00e0 la Sorbonne Universit\u00e9 sous la supervision de M. Bernard Vouilloux avec une bourse d\u2019\u00e9tudes de la FAPESP (Funda\u00e7\u00e3o de Amparo \u00e0 Pesquisa do Estado de S\u00e3o Paulo).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Notes<\/h2>\n\n\n\n<p class=\"has-text-align-justify\">\n\t<a href=\"#sdfootnote1anc\">1<\/a>\n\tSur\n\tl\u2019Id\u00e9e en tant que distincte et n\u00e9cessairement obscure, la\n\tlimite entre la pens\u00e9e et l\u2019impensable, voir : Deleuze, Gilles.\n\t<em>Diff\u00e9rence\n\tet r\u00e9p\u00e9tition<\/em>.\n\t7\u00ba \u00e9dition. Paris : Presses Universitaires de France (PUF), 1993,\n\tp.191.\n\t\n\t<\/p>\n\n\n\n<p class=\"has-text-align-justify\"> <a href=\"#sdfootnote2anc\">2<\/a> \u00c0 propos de Rilke, Blanchot dit que : \u00ab&nbsp;Parler n\u2019est plus dire, ni  nommer. Parler, c\u2019est c\u00e9l\u00e9brer, et c\u00e9l\u00e9brer, c\u2019est glorifier [&#8230;], seul  langage o\u00f9 la nuit et le silence se manifestent sans se rompre ni se  r\u00e9v\u00e9ler&nbsp;\u00bb Blanchot, Maurice. <em>L\u2019espace litt\u00e9raire<\/em>. Paris : Gallimard, 1955, pp.165-166. <br> <\/p>\n\n\n\n<p class=\"has-text-align-justify\"> <a href=\"#sdfootnote3anc\">3<\/a> Pour Deleuze et Guattari, l\u2019image de la pens\u00e9e (orientation dans la  pens\u00e9e) classique est surtout d\u00e9finie en tant que distinction entre la  v\u00e9rit\u00e9 et l&rsquo;erreur, recherche de la v\u00e9rit\u00e9 comme volont\u00e9 et but de toute  la pens\u00e9e. Dans cette distinction, l\u2019erreur a un r\u00f4le m\u00eame plus  important que la v\u00e9rit\u00e9 parce qu\u2019on a besoin de passer par l\u2019erreur pour  arriver \u00e0 la v\u00e9rit\u00e9. Nietzsche a chang\u00e9 cette image de la pens\u00e9e avec  sa \u00ab\u00a0critique de la volont\u00e9 de v\u00e9rit\u00e9\u00a0\u00bb. Apr\u00e8s Nietzsche, ils sont donc,  pour l\u2019image moderne de la pens\u00e9e, les \u00ab&nbsp;cat\u00e9gories comme celles  d&rsquo;Int\u00e9ressant, de Remarquable ou d\u2019Important qui d\u00e9cident de la r\u00e9ussite  ou de l\u2019\u00e9chec&nbsp;\u00bb Deleuze, Gilles ; Guattari, F\u00e9lix. <em>Qu\u2019est-ce que la philosophie ?<\/em> Paris : \u00c9ditions Minuit, 1991, p.84.   <br> <\/p>\n\n\n\n<p class=\"has-text-align-justify\"> <a href=\"#sdfootnote4anc\">4<\/a>  \u00ab&nbsp;Il y a encore des g\u00e9n\u00e9rations mortes qui font des livres pudibonds. M\u00eame des jeunes : des livres <em>charmants<\/em>, sans prolongement aucun, sans nuit. Sans silence&nbsp;\u00bb Duras, Marguerite. <em>\u00c9crire<\/em>. Paris : Gallimard, 1993,  p.34. <br> <\/p>\n\n\n\n<p class=\"has-text-align-justify\">\n\t<a href=\"#sdfootnote5anc\">5<\/a>\n\tTanizaki\n\td\u00e9veloppe une esth\u00e9tique des ombres qui oppose l&rsquo;Orient \u00e0\n\tl&rsquo;Occident. Cette esth\u00e9tique, \u00e0 son tour, peut \u00eatre mise en\n\trelation avec une \u00e9thologie et m\u00eame une ontologie : la diff\u00e9rence\n\tentre les toits japonais, qui servent \u00e0 garder l&rsquo;ombre, et les\n\ttoits occidentaux, qui cherchent la lumi\u00e8re ; la diff\u00e9rence entre\n\tles pierres pr\u00e9cieuses, comme le jade, qui garde un vert opaque,\n\tpar rapport \u00e0 l&rsquo;\u00e9meraude, qui est brillante ; la laque et la\n\tporcelaine ; le <em>Sh\u014dji<\/em>\n\tet la porte vitr\u00e9e, etc. Voir : Tanizaki, Jun\u2019ichiro. <em>\u00c9loge\n\tde l\u2019ombre<\/em>.\n\tTraduction : Ren\u00e9 Sieffert. Paris : Verdier, 2011.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">\n\t<a href=\"#sdfootnote6anc\">6<\/a>\n\t\u00ab&nbsp;L\u2019ivresse\n\test elle-m\u00eame l\u2019absolutisation, le d\u00e9sencha\u00eenement, l&rsquo;ascension\n\tlibre jusqu\u2019au bout du monde. Elle est la jouissance : l\u2019identit\u00e9\n\tdonn\u00e9e dans l\u2019abandon \u00e0 la pouss\u00e9e qui d\u00e9lie l&rsquo;identique, le\n\tcorps r\u00e9sum\u00e9 \u00e0 son spasme, \u00e0 l\u2019arrachement d\u2019un soupir ou\n\td\u2019un \u00e9clat, exclamation entre larme et lave&nbsp;\u00bb Nancy,\n\tJean-Luc. <em>Ivresse<\/em>.\n\tParis : Payot &amp; Rivages, 2013, pp.36-37.<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><a href=\"#sdfootnote7anc\">7<\/a>\n\tVoir&nbsp;: Deleuze, Gilles&nbsp;; Guattari, F\u00e9lix. <em>Qu\u2019est-ce\n\tque la philosophie&nbsp;? <\/em>Paris&nbsp;:\n\tLes \u00c9ditions de Minuit, 1991, p.171. \n\t<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><a href=\"#sdfootnote8anc\">8<\/a>\n\tHofmannsthal, Hugo von.  <em>Lettres\n\tde Lord Chandos et autres textes. <\/em>Traductions\n\tde Jean-Claude Schneider et Albert Kohn. Paris&nbsp;: \u00c9ditions\n\tGallimard, 1992.    \n\t<\/p>\n\n\n\n<p>\n\t<a href=\"#sdfootnote9anc\">9<\/a>\n\tVoir\n\t: Duras, Marguerite. <em>\u00c9crire.\n\t<\/em>Paris\n\t: \u00c9ditions\n\tGallimard,\n\t1993, p.42 ss.<\/p>\n\n\n\n<p>\n\t<a href=\"#sdfootnote10anc\">10<\/a>\n\tVoir\n\t: Didi-Huberman, Georges. <em>Survivance\n\tdes lucioles<\/em>.\n\tParis : Les \u00c9ditions de Minuit, 2009, <em>passim<\/em>.<\/p>\n\n\n\n<p><a href=\"#sdfootnote11anc\">11<\/a>\n\t<em>Idem.<\/em>\n\t\n\t<\/p>\n\n\n\n<p>\n\t<a href=\"#sdfootnote12anc\">12<\/a>\n\tVoir\n\t: Deleuze, Gilles ; Guattari, F\u00e9lix. \u00ab&nbsp;Ann\u00e9e Z\u00e9ro \u2013\n\tVisag\u00e9it\u00e9&nbsp;\u00bb in:\n\t<em>Mille\n\tPlateaux<\/em>,\n\tParis : Les \u00c9ditions de Minuit, 1980, p.222.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">\n\t<a href=\"#sdfootnote13anc\">13<\/a>\n\tCe\n\tn\u2019est pas le cas de Meursault ? \u00ab&nbsp;C\u2019\u00e9tait le m\u00eame soleil\n\tque le jour o\u00f9 j\u2019avais enterr\u00e9 maman et, comme alors, le front\n\tsurtout me faisait mal et toutes ses veines battaient ensemble sous\n\tla peau. \u00c0 cause de cette br\u00fblure que je ne pouvais plus\n\tsupporter, j\u2019ai fait un mouvement en avant. Je savais que c\u2019\u00e9tait\n\tstupide, que je ne me d\u00e9barrasserais pas du soleil en me d\u00e9pla\u00e7ant\n\td\u2019un pas [&#8230;] Et cette fois, sans se soulever, l\u2019Arabe a tir\u00e9\n\tson couteau qu\u2019il m\u2019a pr\u00e9sent\u00e9 dans le soleil. La lumi\u00e8re a\n\tgicl\u00e9 sur l\u2019acier et c\u2019\u00e9tait comme une longue lame \u00e9tincelante\n\tqui m\u2019atteignait au front [&#8230;] Je ne sentais plus que les\n\tcymbales du soleil sur mon front et, indistinctement, le glaive\n\t\u00e9clatant jailli du couteau toujours en face de moi. Cette \u00e9p\u00e9e\n\tbr\u00fblante rongeait mes cils et fouillait mes yeux douloureux&nbsp;\u00bb.\n\tCamus, Albert. <em>L\u2019\u00e9tranger.\n\t<\/em>Paris\n\t: \u00c9ditions Gallimard, 1942, pp.94-95.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">\n\t<a href=\"#sdfootnote14anc\">14<\/a>\n\t\u00ab&nbsp;Des\n\tanimaux h\u00e9berg\u00e9s dans le Nocturama, il me reste sinon en m\u00e9moire\n\tles yeux \u00e9tonnamment grands de certains, et leur regard fixe et\n\tp\u00e9n\u00e9trant, propre aussi \u00e0 ces peintres et philosophes qui tentent\n\tpar la pure vision et la pure pens\u00e9e de percer l\u2019obscurit\u00e9 qui\n\tnous entoure&nbsp;\u00bb Sebald, W. G. <em>Austerlitz<\/em>.\n\tTraduction de Patrick Charbonneau. Paris : Actes du Sud, 2002, p.9.\n\tL&rsquo;une des images accompagnant l&rsquo;extrait ci-dessus est une photo des\n\tyeux de Wittgenstein.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">\n\t<a href=\"#sdfootnote15anc\">15<\/a>\n\tLispector,\n\tClarice. <em>A\n\tma\u00e7\u00e3 no escuro<\/em>.\n\tRio\n\tde Janeiro : Rocco, 1961. Pour l\u2019\u00e9dition fran\u00e7aise : Lispector,\n\tClarice. <em>Le\n\tb\u00e2tisseur de ruines<\/em>.\n\tTraduction de Violante Do Canto. Gallimard : 1970. \n\t<\/p>\n\n\n\n<p class=\"has-text-align-justify\">\n\t<a href=\"#sdfootnote16anc\">16<\/a>\n\tLispector,\n\tClarice. <em>Legi\u00e3o\n\testrangeira<\/em>.\n\tRio de Janeiro : Rocco, 1964. Pour\n\tl\u2019\u00e9dition fran\u00e7aise utilis\u00e9e dans ce texte, voir : Lispector,\n\tClarice. <em>Nouvelles\n\t<\/em>:\n\t\u00e9dition compl\u00e8te. Traduction de Jacques Thi\u00e9riot, Teresa\n\tThi\u00e9riot, Claudia Poncioni, Didier Lamaison, Sylvie Durastanti,\n\tClaude Farny, Genevi\u00e8ve Leibrich et Nicole Biros. Introduction et\n\tnote bibliographique de Benjamin Moser, Paris : \u00c9ditions <em>des\n\tfemmes-<\/em>Antoinette\n\tFouque, 2017, pp.207-208. \n\t<\/p>\n\n\n\n<p>\n\t<a href=\"#sdfootnote17anc\">17<\/a>\n\t<em>Ibidem,\n\t<\/em>pp.207-208.\n\t \n\t<\/p>\n\n\n\n<p>\n\t<a href=\"#sdfootnote18anc\">18<\/a>\n\t<em>Ibidem<\/em>,\n\tp. 208.<\/p>\n\n\n\n<p><a href=\"#sdfootnote19anc\">19<\/a>\n\tQuignard, Pascal. <em>Rh\u00e9torique\n\tsp\u00e9culative. <\/em>Paris&nbsp;:\n\tCalmann-L\u00e9vy, 1995. \n\t\n\t<\/p>\n\n\n\n<p> <a href=\"#sdfootnote20anc\">20<\/a> <em>Ibidem<\/em>, p. 209.<\/p>\n\n\n\n<p class=\"has-text-align-justify\"> <a href=\"#sdfootnote21anc\">21<\/a> Sur le \u00ab&nbsp;sens&nbsp;\u00bb en tant qu\u2019\u00e9v\u00e9nement, \u00ab&nbsp;l\u2019exprim\u00e9 de la proposition&nbsp;\u00bb, voir&nbsp;: Deleuze, Gilles. <em>Logique du sens<\/em>. Paris&nbsp;: Les \u00c9ditions de Minuit, 1969, pp.41-49.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab&nbsp;Une mouche \u00e9ph\u00e9m\u00e8re na\u00eet \u00e0 neuf heures du matin dans les grands jours d\u2019\u00e9t\u00e9, pour mourir \u00e0 cinq heures du soir ; comment comprendrait-elle le mot nuit ?&nbsp;\u00bb Stendhal La naissance de la lumi\u00e8re, r\u00e9sistance de la nuit Avant la lumi\u00e8re, la nuit \u00e9tait l\u00e0. Mais pas m\u00eame le dieu jud\u00e9o-chr\u00e9tien n&rsquo;a pu supporter la [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[109],"tags":[149,150,116,151],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8FFEZ-dG","jetpack-related-posts":[{"id":879,"url":"https:\/\/www.esquisses.eu\/revue\/la-nuit-un-scenario-pour-la-lumiere-luis-meyer\/","url_meta":{"origin":848,"position":0},"title":"La nuit &#8211; un sc\u00e9nario pour la lumi\u00e8re \u2014 Luis Meyer","author":"Administrateur","date":"3 juillet 2023","format":false,"excerpt":"Nuit, le PDF Chaque homme dans sa nuit s'en va vers la lumi\u00e8re Victor Hugo Ce travail propose une r\u00e9flexion autour des liens de la nuit avec le noir, \u00e0 partir de l'int\u00e9r\u00eat pour la d\u00e9couverte de diff\u00e9rentes situations \u00e0 titre personnel dans lesquelles la pr\u00e9sence du noir me permet\u2026","rel":"","context":"Dans &quot;NUIT&quot;","block_context":{"text":"NUIT","link":"https:\/\/www.esquisses.eu\/revue\/category\/nuit\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.esquisses.eu\/revue\/wp-content\/uploads\/2023\/09\/meyer1.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":883,"url":"https:\/\/www.esquisses.eu\/revue\/nuit-esquive-valentine-oncins\/","url_meta":{"origin":848,"position":1},"title":"Nuit esquive \u2014 Valentine Oncins","author":"Administrateur","date":"27 ao\u00fbt 2023","format":false,"excerpt":"Nuit, le PDF Les photographies de Valentine Oncins furent expos\u00e9es \u00e0 la galerie Ph\u00e9n(o), 11 rue de la Fontaine \u00e0 Montpellier du 3 juin au 3 septembre 2023. Porte ouverte \u00e0 l\u2019effacement du monde, la nuit est une place forte del\u2019Ouvert. Elle est un livre blanc, \u00e0 raturer \u00e0 coups\u2026","rel":"","context":"Dans &quot;NUIT&quot;","block_context":{"text":"NUIT","link":"https:\/\/www.esquisses.eu\/revue\/category\/nuit\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.esquisses.eu\/revue\/wp-content\/uploads\/2023\/08\/fond-blanc.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1116,"url":"https:\/\/www.esquisses.eu\/revue\/exposition-nuit-a-la-galerie-pheno-lucille-breard\/","url_meta":{"origin":848,"position":2},"title":"Exposition Nuit \u00e0 la galerie Ph\u00e9no \u2014 Lucille Br\u00e9ard","author":"Administrateur","date":"6 septembre 2023","format":false,"excerpt":"Nuit, le PDF La revue a \u00e9galement ouvert son appel \u00e0 des propositions artistiques. En collaboration avec la galerie-atelier Ph\u00e9no, situ\u00e9e \u00e0 Montpellier, Esquisses a permis \u00e0 ces trois artistes de participer \u00e0 l'exposition \"Nuit\", du 3 juin au 3 septembre 2023. Cette th\u00e9matique a donc pu questionner l'esth\u00e9tique \u00e0\u2026","rel":"","context":"Dans &quot;NUIT&quot;","block_context":{"text":"NUIT","link":"https:\/\/www.esquisses.eu\/revue\/category\/nuit\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.esquisses.eu\/revue\/wp-content\/uploads\/2023\/09\/IMG_20230603_014517_905-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1098,"url":"https:\/\/www.esquisses.eu\/revue\/aux-frontieres-de-la-nuit-marc-courtieu\/","url_meta":{"origin":848,"position":3},"title":"Aux fronti\u00e8res de la nuit \u2014 Marc Courtieu","author":"Administrateur","date":"6 septembre 2023","format":false,"excerpt":"Nuit, le PDF Prendre la nuit comme un pays un peu myst\u00e9rieux, un peu effrayant, difficile \u00e0 p\u00e9n\u00e9trer, qui se d\u00e9robe au fur et \u00e0 mesure qu\u2019on tente de s\u2019y glisser\u2026 Pour nous, animaux diurnes, le nocturne fait peur\u00a0: plut\u00f4t que de l\u2019affronter, on pr\u00e9f\u00e8re souvent y dormir \u2013 cela\u2026","rel":"","context":"Dans &quot;NUIT&quot;","block_context":{"text":"NUIT","link":"https:\/\/www.esquisses.eu\/revue\/category\/nuit\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.esquisses.eu\/revue\/wp-content\/uploads\/2023\/08\/fond-blanc.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1095,"url":"https:\/\/www.esquisses.eu\/revue\/nuit-de-la-conscience-dapres-deep-me-de-marc-antoine-mathieu-pauline-desiderio\/","url_meta":{"origin":848,"position":4},"title":"Nuit de la conscience, D&rsquo;apr\u00e8s Deep me de Marc-Antoine Mathieu \u2014 Pauline Desiderio","author":"Administrateur","date":"6 septembre 2023","format":false,"excerpt":"Nuit, le PDF \u00ab Mais quand tu as une certitude, n\u2019est-ce pas simplement parce que tu fermes les yeux devant le doute ? \u00bb \u2013 Ils sont ferm\u00e9s. Recherches Philosophiques, Ludwig Wittgenstein Marc-Antoine Mathieu est un auteur qui aime chercher voire transgresser les limites de la narration visuelle dans la\u2026","rel":"","context":"Dans &quot;NUIT&quot;","block_context":{"text":"NUIT","link":"https:\/\/www.esquisses.eu\/revue\/category\/nuit\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":849,"url":"https:\/\/www.esquisses.eu\/revue\/vergers-nocturnes-bronwyn-louw\/","url_meta":{"origin":848,"position":5},"title":"Vergers nocturnes \u2014 Bronwyn Louw","author":"Administrateur","date":"29 juin 2023","format":false,"excerpt":"Nuit, le PDF \u00ab\u00a0Le verger est le symbole durable de la cultivation pastorale. Soign\u00e9 ou vieux, entretenu ou n\u00e9glig\u00e9, le verger donne des fruits et des g\u00e9n\u00e9alogies, simultan\u00e9ment pomologiques et litt\u00e9raires\u00a0\u00bb \u00e9crit la critique Mary Jacobus, pointant le caract\u00e8re mat\u00e9riel-s\u00e9miotique du verger, en m\u00eame temps un topos litt\u00e9raire vieux comme\u2026","rel":"","context":"Dans &quot;NUIT&quot;","block_context":{"text":"NUIT","link":"https:\/\/www.esquisses.eu\/revue\/category\/nuit\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.esquisses.eu\/revue\/wp-content\/uploads\/2023\/06\/Poeme34-1.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.esquisses.eu\/revue\/wp-json\/wp\/v2\/posts\/848"}],"collection":[{"href":"https:\/\/www.esquisses.eu\/revue\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esquisses.eu\/revue\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esquisses.eu\/revue\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esquisses.eu\/revue\/wp-json\/wp\/v2\/comments?post=848"}],"version-history":[{"count":7,"href":"https:\/\/www.esquisses.eu\/revue\/wp-json\/wp\/v2\/posts\/848\/revisions"}],"predecessor-version":[{"id":1293,"href":"https:\/\/www.esquisses.eu\/revue\/wp-json\/wp\/v2\/posts\/848\/revisions\/1293"}],"wp:attachment":[{"href":"https:\/\/www.esquisses.eu\/revue\/wp-json\/wp\/v2\/media?parent=848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esquisses.eu\/revue\/wp-json\/wp\/v2\/categories?post=848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esquisses.eu\/revue\/wp-json\/wp\/v2\/tags?post=848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}